{"id":3693,"date":"2011-10-19T21:49:00","date_gmt":"2011-10-19T21:49:00","guid":{"rendered":"https:\/\/www.hww.ca\/passez-a-laction\/action-et-sensibilisation\/faites-front-commun-contre-linvasion-des-especes-exotiques\/"},"modified":"2024-11-18T20:46:34","modified_gmt":"2024-11-18T20:46:34","slug":"faites-front-commun-contre-linvasion-des-especes-exotiques","status":"publish","type":"page","link":"https:\/\/www.hww.ca\/fr\/passez-a-laction\/action-et-sensibilisation\/faites-front-commun-contre-linvasion-des-especes-exotiques\/","title":{"rendered":"Faites front commun contre l&#8217;invasion des esp\u00e8ces exotiques"},"content":{"rendered":"<p>Lorsque des esp&egrave;ces non indig&egrave;nes sont introduites au Canada, souvent dans les citernes &agrave; ballast des navires ou &agrave; bord de camions ou de trains, elles peuvent se multiplier rapidement, perturbant les esp&egrave;ces indig&egrave;nes et les &eacute;cosyst&egrave;mes. Prenons, par exemple, le Bythotrephes caderstroemi (cladoc&egrave;re pr&eacute;dateur). Ce crustac&eacute; europ&eacute;en est arriv&eacute; en Am&eacute;rique du Nord en 1984. En moins de trois ans, ce minuscule envahisseur s&rsquo;&eacute;tait r&eacute;pandu dans tous les Grands Lacs et ailleurs, faisant la lutte aux esp&egrave;ces indig&egrave;nes pour l&rsquo;approvisionnement limit&eacute; de nourriture. La gr&eacute;mille eurasienne et le gobie sont des poissons envahisseurs agressifs dont la population s&rsquo;est accrue &agrave; un rythme alarmant au cours des dix derni&egrave;res ann&eacute;es. Ils d&eacute;vorent les oeufs et les jeunes des autres poissons et leur font concurrence pour la nourriture.<\/p>\n<p>La dreissena polymorphe est encore plus r&eacute;pandue. Une seule de ces moules z&eacute;br&eacute;es blanc et noir d&rsquo;eau douce peut produire un million d&rsquo;&oelig;ufs par ann&eacute;e, formant des masses de 750,000 oeufs par m&egrave;tre carr&eacute;. Elles s&rsquo;accrochent &agrave; toute surface &#8211; conduites d&rsquo;eau, coques de navires, bou&eacute;es et animaux comme les &eacute;crevisses et les palourdes -et elles &eacute;touffent les fray&egrave;res.<\/p>\n<p>L&rsquo;esp&egrave;ce exotique la plus visible est la salicaire, une plante capable d&rsquo;&eacute;touffer toutes les plantes indig&egrave;nes et de former des rangs imp&eacute;n&eacute;trables qui ne fournissent ni abri, ni nourriture &agrave; la faune, et d&eacute;truisent les aires de nidification. Comme chaque plante produit pr&egrave;s de trois millions de graines par ann&eacute;e, la salicaire a infest&eacute; toutes les provinces du Canada.<\/p>\n<p>Voici ce que vous pouvez faire pour enrayer l&rsquo;invasion des esp&egrave;ces exotiques :<\/p>\n<ul>\n<li>Apprenez &agrave; identifier et &agrave; rep&eacute;rer les plantes et les animaux exotiques. Par exemple, un bon moyen de rep&eacute;rer la dreissena polymorphe est de suspendre une pierre &agrave; un c&acirc;ble au bout d&rsquo;un quai et de v&eacute;rifier la pr&eacute;sence de masse de ces mollusques. Vous pouvez vous procurer des brochures sur l&rsquo;identification des esp&egrave;ces exotiques aupr&egrave;s des organismes de protection de la faune inscrits sur la couverture arri&egrave;re de la pr&eacute;sente publication.<\/li>\n<li>Si vous soup&ccedil;onnez qu&rsquo;une nouvelle invasion d&rsquo;esp&egrave;ces non indig&egrave;nes a eu lieu, signalez-la &agrave; votre minist&egrave;re des Ressources naturelles ou &agrave; la F&eacute;d&eacute;ration canadienne de la faune.<\/li>\n<li>Lancez un programme &eacute;ducatif &agrave; l&rsquo;intention des plaisanciers, des p&ecirc;cheurs, des plongeurs et des propri&eacute;taires de demeures riveraines pour pr&eacute;venir la prolif&eacute;ration des envahisseurs aquatiques.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Lorsque des esp&egrave;ces non indig&egrave;nes sont introduites au Canada, souvent dans les citernes &agrave; ballast des navires ou &agrave; bord de camions ou de trains, elles peuvent se multiplier rapidement, perturbant les esp&egrave;ces indig&egrave;nes et les &eacute;cosyst&egrave;mes. Prenons, par exemple, le Bythotrephes caderstroemi (cladoc&egrave;re pr&eacute;dateur). Ce crustac&eacute; europ&eacute;en est arriv&eacute; en Am&eacute;rique du Nord en [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":650,"parent":2277,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","footnotes":""},"class_list":["post-3693","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Faites front commun contre l&#039;invasion des esp\u00e8ces exotiques - Faune et Flore du Pays<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.hww.ca\/fr\/passez-a-laction\/action-et-sensibilisation\/faites-front-commun-contre-linvasion-des-especes-exotiques\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Faites front commun contre l&#039;invasion des esp\u00e8ces exotiques - Faune et Flore du Pays\" \/>\n<meta property=\"og:description\" content=\"Lorsque des esp&egrave;ces non indig&egrave;nes sont introduites au Canada, souvent dans les citernes &agrave; ballast des navires ou &agrave; bord de camions ou de trains, elles peuvent se multiplier rapidement, perturbant les esp&egrave;ces indig&egrave;nes et les &eacute;cosyst&egrave;mes. Prenons, par exemple, le Bythotrephes caderstroemi (cladoc&egrave;re pr&eacute;dateur). Ce crustac&eacute; europ&eacute;en est arriv&eacute; en Am&eacute;rique du Nord en [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.hww.ca\/fr\/passez-a-laction\/action-et-sensibilisation\/faites-front-commun-contre-linvasion-des-especes-exotiques\/\" \/>\n<meta property=\"og:site_name\" content=\"Faune et Flore du Pays\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-18T20:46:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.hww.ca\/wp-content\/uploads\/2014\/12\/Peatlands.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"615\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.hww.ca\\\/fr\\\/passez-a-laction\\\/action-et-sensibilisation\\\/faites-front-commun-contre-linvasion-des-especes-exotiques\\\/\",\"url\":\"https:\\\/\\\/www.hww.ca\\\/fr\\\/passez-a-laction\\\/action-et-sensibilisation\\\/faites-front-commun-contre-linvasion-des-especes-exotiques\\\/\",\"name\":\"Faites front commun contre l'invasion des esp\u00e8ces exotiques - Faune et Flore du Pays\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hww.ca\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.hww.ca\\\/fr\\\/passez-a-laction\\\/action-et-sensibilisation\\\/faites-front-commun-contre-linvasion-des-especes-exotiques\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hww.ca\\\/fr\\\/passez-a-laction\\\/action-et-sensibilisation\\\/faites-front-commun-contre-linvasion-des-especes-exotiques\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.hww.ca\\\/wp-content\\\/uploads\\\/2014\\\/12\\\/Peatlands.jpg\",\"datePublished\":\"2011-10-19T21:49:00+00:00\",\"dateModified\":\"2024-11-18T20:46:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.hww.ca\\\/fr\\\/passez-a-laction\\\/action-et-sensibilisation\\\/faites-front-commun-contre-linvasion-des-especes-exotiques\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.hww.ca\\\/fr\\\/passez-a-laction\\\/action-et-sensibilisation\\\/faites-front-commun-contre-linvasion-des-especes-exotiques\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.hww.ca\\\/fr\\\/passez-a-laction\\\/action-et-sensibilisation\\\/faites-front-commun-contre-linvasion-des-especes-exotiques\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.hww.ca\\\/wp-content\\\/uploads\\\/2014\\\/12\\\/Peatlands.jpg\",\"contentUrl\":\"https:\\\/\\\/www.hww.ca\\\/wp-content\\\/uploads\\\/2014\\\/12\\\/Peatlands.jpg\",\"width\":960,\"height\":615,\"caption\":\"Les tourbi\u00e8res\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.hww.ca\\\/fr\\\/passez-a-laction\\\/action-et-sensibilisation\\\/faites-front-commun-contre-linvasion-des-especes-exotiques\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"accueil\",\"item\":\"https:\\\/\\\/www.hww.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Passez \u00e0 l\u2019action\",\"item\":\"https:\\\/\\\/www.hww.ca\\\/fr\\\/passez-a-laction\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Action et sensibilisation\",\"item\":\"https:\\\/\\\/www.hww.ca\\\/fr\\\/passez-a-laction\\\/action-et-sensibilisation\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Faites front commun contre l&rsquo;invasion des esp\u00e8ces exotiques\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.hww.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.hww.ca\\\/fr\\\/\",\"name\":\"Faune et Flore du Pays\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.hww.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Faites front commun contre l'invasion des esp\u00e8ces exotiques - Faune et Flore du Pays","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.hww.ca\/fr\/passez-a-laction\/action-et-sensibilisation\/faites-front-commun-contre-linvasion-des-especes-exotiques\/","og_locale":"fr_FR","og_type":"article","og_title":"Faites front commun contre l'invasion des esp\u00e8ces exotiques - Faune et Flore du Pays","og_description":"Lorsque des esp&egrave;ces non indig&egrave;nes sont introduites au Canada, souvent dans les citernes &agrave; ballast des navires ou &agrave; bord de camions ou de trains, elles peuvent se multiplier rapidement, perturbant les esp&egrave;ces indig&egrave;nes et les &eacute;cosyst&egrave;mes. Prenons, par exemple, le Bythotrephes caderstroemi (cladoc&egrave;re pr&eacute;dateur). Ce crustac&eacute; europ&eacute;en est arriv&eacute; en Am&eacute;rique du Nord en [&hellip;]","og_url":"https:\/\/www.hww.ca\/fr\/passez-a-laction\/action-et-sensibilisation\/faites-front-commun-contre-linvasion-des-especes-exotiques\/","og_site_name":"Faune et Flore du Pays","article_modified_time":"2024-11-18T20:46:34+00:00","og_image":[{"width":960,"height":615,"url":"https:\/\/www.hww.ca\/wp-content\/uploads\/2014\/12\/Peatlands.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.hww.ca\/fr\/passez-a-laction\/action-et-sensibilisation\/faites-front-commun-contre-linvasion-des-especes-exotiques\/","url":"https:\/\/www.hww.ca\/fr\/passez-a-laction\/action-et-sensibilisation\/faites-front-commun-contre-linvasion-des-especes-exotiques\/","name":"Faites front commun contre l'invasion des esp\u00e8ces exotiques - Faune et Flore du Pays","isPartOf":{"@id":"https:\/\/www.hww.ca\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.hww.ca\/fr\/passez-a-laction\/action-et-sensibilisation\/faites-front-commun-contre-linvasion-des-especes-exotiques\/#primaryimage"},"image":{"@id":"https:\/\/www.hww.ca\/fr\/passez-a-laction\/action-et-sensibilisation\/faites-front-commun-contre-linvasion-des-especes-exotiques\/#primaryimage"},"thumbnailUrl":"https:\/\/www.hww.ca\/wp-content\/uploads\/2014\/12\/Peatlands.jpg","datePublished":"2011-10-19T21:49:00+00:00","dateModified":"2024-11-18T20:46:34+00:00","breadcrumb":{"@id":"https:\/\/www.hww.ca\/fr\/passez-a-laction\/action-et-sensibilisation\/faites-front-commun-contre-linvasion-des-especes-exotiques\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.hww.ca\/fr\/passez-a-laction\/action-et-sensibilisation\/faites-front-commun-contre-linvasion-des-especes-exotiques\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.hww.ca\/fr\/passez-a-laction\/action-et-sensibilisation\/faites-front-commun-contre-linvasion-des-especes-exotiques\/#primaryimage","url":"https:\/\/www.hww.ca\/wp-content\/uploads\/2014\/12\/Peatlands.jpg","contentUrl":"https:\/\/www.hww.ca\/wp-content\/uploads\/2014\/12\/Peatlands.jpg","width":960,"height":615,"caption":"Les tourbi\u00e8res"},{"@type":"BreadcrumbList","@id":"https:\/\/www.hww.ca\/fr\/passez-a-laction\/action-et-sensibilisation\/faites-front-commun-contre-linvasion-des-especes-exotiques\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"accueil","item":"https:\/\/www.hww.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Passez \u00e0 l\u2019action","item":"https:\/\/www.hww.ca\/fr\/passez-a-laction\/"},{"@type":"ListItem","position":3,"name":"Action et sensibilisation","item":"https:\/\/www.hww.ca\/fr\/passez-a-laction\/action-et-sensibilisation\/"},{"@type":"ListItem","position":4,"name":"Faites front commun contre l&rsquo;invasion des esp\u00e8ces exotiques"}]},{"@type":"WebSite","@id":"https:\/\/www.hww.ca\/fr\/#website","url":"https:\/\/www.hww.ca\/fr\/","name":"Faune et Flore du Pays","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.hww.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/www.hww.ca\/fr\/wp-json\/wp\/v2\/pages\/3693","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hww.ca\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.hww.ca\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.hww.ca\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hww.ca\/fr\/wp-json\/wp\/v2\/comments?post=3693"}],"version-history":[{"count":1,"href":"https:\/\/www.hww.ca\/fr\/wp-json\/wp\/v2\/pages\/3693\/revisions"}],"predecessor-version":[{"id":3694,"href":"https:\/\/www.hww.ca\/fr\/wp-json\/wp\/v2\/pages\/3693\/revisions\/3694"}],"up":[{"embeddable":true,"href":"https:\/\/www.hww.ca\/fr\/wp-json\/wp\/v2\/pages\/2277"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hww.ca\/fr\/wp-json\/wp\/v2\/media\/650"}],"wp:attachment":[{"href":"https:\/\/www.hww.ca\/fr\/wp-json\/wp\/v2\/media?parent=3693"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}